{"id":299,"date":"2022-05-20T08:41:57","date_gmt":"2022-05-20T08:41:57","guid":{"rendered":"https:\/\/www.acoem.com\/brazil\/pt-br\/?page_id=299"},"modified":"2023-08-18T09:19:35","modified_gmt":"2023-08-18T09:19:35","slug":"representantes-locais","status":"publish","type":"page","link":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/","title":{"rendered":"Encontre seus representantes locais"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.<\/p>\n","protected":false},"author":25,"featured_media":0,"parent":298,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":""},"class_list":["post-299","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encontre seus representantes locais - Acoem Brasil<\/title>\n<meta name=\"description\" content=\"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encontre seus representantes locais - Acoem Brasil\" \/>\n<meta property=\"og:description\" content=\"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/\" \/>\n<meta property=\"og:site_name\" content=\"Acoem Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T09:19:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/representantes-locais\\\/\",\"url\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/representantes-locais\\\/\",\"name\":\"Encontre seus representantes locais - Acoem Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/#website\"},\"datePublished\":\"2022-05-20T08:41:57+00:00\",\"dateModified\":\"2023-08-18T09:19:35+00:00\",\"description\":\"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/representantes-locais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/representantes-locais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/representantes-locais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre n\u00f3s\",\"item\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/sobre-nos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Encontre seus representantes locais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/\",\"name\":\"Acoem Brasil\",\"description\":\"Just another Les sites de ACOEM site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.acoem.com\\\/brasil\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encontre seus representantes locais - Acoem Brasil","description":"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/","og_locale":"pt_BR","og_type":"article","og_title":"Encontre seus representantes locais - Acoem Brasil","og_description":"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.","og_url":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/","og_site_name":"Acoem Brasil","article_modified_time":"2023-08-18T09:19:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/","url":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/","name":"Encontre seus representantes locais - Acoem Brasil","isPartOf":{"@id":"https:\/\/www.acoem.com\/brasil\/pt-br\/#website"},"datePublished":"2022-05-20T08:41:57+00:00","dateModified":"2023-08-18T09:19:35+00:00","description":"A Acoem estabelece uma presen\u00e7a mundial para fornecer solu\u00e7\u00f5es inovadoras e limitar seu impacto ambiental.","breadcrumb":{"@id":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/representantes-locais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.acoem.com\/brasil\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Sobre n\u00f3s","item":"https:\/\/www.acoem.com\/brasil\/pt-br\/sobre-nos\/"},{"@type":"ListItem","position":3,"name":"Encontre seus representantes locais"}]},{"@type":"WebSite","@id":"https:\/\/www.acoem.com\/brasil\/pt-br\/#website","url":"https:\/\/www.acoem.com\/brasil\/pt-br\/","name":"Acoem Brasil","description":"Just another Les sites de ACOEM site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.acoem.com\/brasil\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/pages\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":1,"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/pages\/299\/revisions"}],"predecessor-version":[{"id":302,"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/pages\/299\/revisions\/302"}],"up":[{"embeddable":true,"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/pages\/298"}],"wp:attachment":[{"href":"https:\/\/www.acoem.com\/brasil\/pt-br\/wp-json\/wp\/v2\/media?parent=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}